{"id":36,"count":4,"description":"","link":"https:\/\/securlift.ca\/en\/category\/new-forklifts-stock\/electrical-new\/","name":"Electrical \u2013 New","slug":"electrical-new","taxonomy":"category","parent":35,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Electrical \u2013 New Archives - Secur Lift<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/securlift.ca\/en\/category\/new-forklifts-stock\/electrical-new\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Electrical \u2013 New Archives - Secur Lift\" \/>\n<meta property=\"og:url\" content=\"https:\/\/securlift.ca\/en\/category\/new-forklifts-stock\/electrical-new\/\" \/>\n<meta property=\"og:site_name\" content=\"Secur Lift\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/securlift.ca\/en\/category\/new-forklifts-stock\/electrical-new\/\",\"url\":\"https:\/\/securlift.ca\/en\/category\/new-forklifts-stock\/electrical-new\/\",\"name\":\"Electrical \u2013 New Archives - Secur Lift\",\"isPartOf\":{\"@id\":\"https:\/\/securlift.ca\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/securlift.ca\/en\/category\/new-forklifts-stock\/electrical-new\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/securlift.ca\/en\/category\/new-forklifts-stock\/electrical-new\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/securlift.ca\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New forklifts - Stock\",\"item\":\"https:\/\/securlift.ca\/en\/category\/new-forklifts-stock\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Electrical \u2013 New\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/securlift.ca\/en\/#website\",\"url\":\"https:\/\/securlift.ca\/en\/\",\"name\":\"Secur Lift\",\"description\":\"Sp\u00e9cialiste en m\u00e9canique de v\u00e9hicule de construction et manutention\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/securlift.ca\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Electrical \u2013 New Archives - Secur Lift","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/securlift.ca\/en\/category\/new-forklifts-stock\/electrical-new\/","og_locale":"en_US","og_type":"article","og_title":"Electrical \u2013 New Archives - Secur Lift","og_url":"https:\/\/securlift.ca\/en\/category\/new-forklifts-stock\/electrical-new\/","og_site_name":"Secur Lift","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/securlift.ca\/en\/category\/new-forklifts-stock\/electrical-new\/","url":"https:\/\/securlift.ca\/en\/category\/new-forklifts-stock\/electrical-new\/","name":"Electrical \u2013 New Archives - Secur Lift","isPartOf":{"@id":"https:\/\/securlift.ca\/en\/#website"},"breadcrumb":{"@id":"https:\/\/securlift.ca\/en\/category\/new-forklifts-stock\/electrical-new\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/securlift.ca\/en\/category\/new-forklifts-stock\/electrical-new\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/securlift.ca\/en\/"},{"@type":"ListItem","position":2,"name":"New forklifts - Stock","item":"https:\/\/securlift.ca\/en\/category\/new-forklifts-stock\/"},{"@type":"ListItem","position":3,"name":"Electrical \u2013 New"}]},{"@type":"WebSite","@id":"https:\/\/securlift.ca\/en\/#website","url":"https:\/\/securlift.ca\/en\/","name":"Secur Lift","description":"Sp\u00e9cialiste en m\u00e9canique de v\u00e9hicule de construction et manutention","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/securlift.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/securlift.ca\/en\/wp-json\/wp\/v2\/categories\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/securlift.ca\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/securlift.ca\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/securlift.ca\/en\/wp-json\/wp\/v2\/categories\/35"}],"wp:post_type":[{"href":"https:\/\/securlift.ca\/en\/wp-json\/wp\/v2\/posts?categories=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}